{"id":7929,"date":"2026-05-13T16:43:21","date_gmt":"2026-05-13T16:43:21","guid":{"rendered":"https:\/\/lavereda.com.mx\/?p=7929"},"modified":"2026-05-13T16:43:21","modified_gmt":"2026-05-13T16:43:21","slug":"a-la-hora-del-cafe-18","status":"publish","type":"post","link":"https:\/\/lavereda.com.mx\/index.php\/2026\/05\/13\/a-la-hora-del-cafe-18\/","title":{"rendered":"A la hora del caf\u00e9"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Precariedad<\/h3>\n\n\n\n<p>Martes a las 19:00 horas, la hora pico del tr\u00e1fico, me dirijo al primer cuadro de la ciudad, a la zona del sector de la salud privada, con tan solo unas gotas de gasolina en el carro y los \u00faltimos pesos de una quincena, corta, precaria. La meta es comprar el medicamento de un familiar. El clima ha cambiado d\u00e1ndole la bienvenida al denso calor de mayo, la respiraci\u00f3n ser\u00e1 pesada, dif\u00edcil, como lo es transitar en esta ciudad, que nos desquicia por el tr\u00e1fico, que nos ha hecho resilientes ante un clima poco amable, con pocas \u00e1reas verdes.<\/p>\n\n\n\n<p>Me detengo en la gasolinera m\u00e1s cercana despu\u00e9s de que se encendi\u00f3 el foco rojo de la gasolina. Hay que cargar combustible con lo poco que queda en la cuenta. Apenas es martes, ya me siento cansada, ojos con ojeras, maquillaje corrido. Entonces la veo a ella, una mujer contenta, reci\u00e9n peinada y reci\u00e9n maquillada. A lo lejos me hace una se\u00f1a, me pide que me acerque a la bomba de gasolina que est\u00e1 por desocuparse. \u00bfQui\u00e9n te pide amablemente que vayas a echar gasolina? \u00bfA qui\u00e9n no le toca ir a las gasolineras siempre llenas de autos con despachadores atareados, acalorados, despu\u00e9s de horas de estar en pie?<\/p>\n\n\n\n<p>Ella ten\u00eda esa mirada de quien quiere hacer las cosas bien. Su uniforme pulcro, su peinado liso. Me dirig\u00ed al lugar y lo primero que pens\u00e9 fue en que no ten\u00eda monedas para darle una buena propina a esa trabajadora, mi cartera estaba vac\u00eda. Me sent\u00ed mal de no poder contribuir, por fin, a una cara amable. \u00bfQu\u00e9 hay detr\u00e1s de las mujeres que trabajan despachando gasolina? Si su hora de entrada era a las 19:00 horas, su hora de salida posiblemente ser\u00eda a las 2:00 de la ma\u00f1ana. Antes de acercarse a mi coche, ella se persign\u00f3 como signo de un buen augurio en su jornada laboral. Me despach\u00f3 amable, con buen \u00e1nimo, con gusto me baj\u00e9 del coche para pagar los litros de gasolina que me llevar\u00edan de nuevo al trabajo y despu\u00e9s a mi casa.<\/p>\n\n\n\n<p>Entonces reson\u00f3 en mi mente la letra de una canci\u00f3n del dueto peruano Alejandro y Mar\u00eda Laura \u201cAlgo tiene que estar mal\u201d:<\/p>\n\n\n\n<p><em>Me voy<br>De la casa a la oficina<br>Me acostumbr\u00e9 a la rutina<br>Las deudas se van pagando con cafe\u00edna<\/em><\/p>\n\n\n\n<p><em>Algo tiene que cambiar<br>El que la sigue no siempre la consigue<br>El que trabaja menos es el que m\u00e1s recibe<br>Algo tiene que estar mal.<\/em><\/p>\n\n\n\n<p>En una misma ciudad la precariedad se vive diferente de una familia a otra, pero cuando llega la noche, cuando se oscurece y algunas madres de familia van regresando a su casa a hacer de cenar y a convivir un rato con sus hijos, la sensaci\u00f3n de estar perdiendo un poco de vida siempre aparece.<\/p>\n\n\n\n<p><em>Me voy sin hacer mucho ruido<br>Y cuando regreso ya se han dormido<br>Te cambio mi sueldo por horas de sue\u00f1o<br>Por cada momento que me he perdido<\/em><\/p>\n\n\n\n<p>\u00bfEs normal tener un trabajo con un sueldo m\u00ednimo? \u00bfEs normal tener dos o tres empleos para salir medianamente adelante? la clase trabajadora se desgasta el doble que muchas personas para ganar un m\u00ednimo porcentaje de quienes acceden a sueldos, por ejemplo, de la clase pol\u00edtica.<\/p>\n\n\n\n<p>Esa tarde regres\u00e9 cansada como siempre a casa, me sent\u00ed privilegiada por tener un sitio a donde llegar, ponerme el pijama, hacer de cenar y descansar.<\/p>\n\n\n\n<p>X @Lavargasadri<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Precariedad Martes a las 19:00 horas, la hora pico del tr\u00e1fico, me dirijo al primer cuadro de la ciudad, a la zona del sector de la salud privada, con tan &hellip; <a href=\"https:\/\/lavereda.com.mx\/index.php\/2026\/05\/13\/a-la-hora-del-cafe-18\/\" class=\"more-link\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":9,"featured_media":7930,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-7929","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-opinion","entry"],"_links":{"self":[{"href":"https:\/\/lavereda.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/7929","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lavereda.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lavereda.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lavereda.com.mx\/index.php\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/lavereda.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=7929"}],"version-history":[{"count":1,"href":"https:\/\/lavereda.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/7929\/revisions"}],"predecessor-version":[{"id":7931,"href":"https:\/\/lavereda.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/7929\/revisions\/7931"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lavereda.com.mx\/index.php\/wp-json\/wp\/v2\/media\/7930"}],"wp:attachment":[{"href":"https:\/\/lavereda.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=7929"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lavereda.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=7929"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lavereda.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=7929"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}